{"id":441,"count":8,"description":"","link":"http:\/\/batimedianews.com\/live\/index.php\/category\/mobilier\/","name":"Mobilier","slug":"mobilier","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/categories\/441"}],"collection":[{"href":"http:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/posts?categories=441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}