{"id":2656,"date":"2019-09-09T16:17:42","date_gmt":"2019-09-09T14:17:42","guid":{"rendered":"http:\/\/batimedianews.com\/live\/?p=2656"},"modified":"2019-09-09T16:17:42","modified_gmt":"2019-09-09T14:17:42","slug":"cellumat-construire-en-monomur-en-beton-cellulaire","status":"publish","type":"post","link":"http:\/\/batimedianews.com\/live\/index.php\/2019\/09\/09\/cellumat-construire-en-monomur-en-beton-cellulaire\/","title":{"rendered":"Cellumat : Construire en monomur en b\u00e9ton cellulaire"},"content":{"rendered":"\n<p>MONOMUR EN B\u00c9TON CELLULAIRE :  DES CONSTRUCTIONS  PARFAITEMENT \u00c9TANCHES \u00c0 L\u2019AIR,  FACILES \u00c0 METTRE EN OEUVRE ET SANS ISOLANTS RAPPORT\u00c9S<\/p>\n\n\n\n<p style=\"text-align:justify\">Le b\u00e9ton cellulaire apporte une v\u00e9ritable solution monomur. En construisant avec les solutions Cellumat monomur, on r\u00e9pond de fa\u00e7on simple et \u00e9conomique aux crit\u00e8res thermiques de la RT et m\u00eame de la norme passive.Comme le t\u00e9moigne Stanislas Della Valle, architecte de l\u2019Atelier d\u2019Architecture Della Valle, le b\u00e9ton cellulaire est d\u2019une grande force portante, \u00e9tanche \u00e0 l\u2019air et sans ponts thermiques, avec un pouvoir isolant exceptionnel. Il permet de construire sans mat\u00e9riaux d\u2019isolation suppl\u00e9mentaires et simplifie la question des noeuds constructifs. En effet, de par leur structure, compos\u00e9e de +\/- 80% d\u2019air, les solutions ENERGIEBLOC et PASSIFBLOC permettent d\u2019\u00eatre jusqu\u2019\u00e0 5 fois plus isolants que d\u2019autres mat\u00e9riaux de construction porteurs isolants et atteignent automatiquement des valeurs Psi et des facteurs de temp\u00e9-rature in\u00e9gal\u00e9s. Par ailleurs, comme le confirme Thierry Giambelluco, g\u00e9rant de Bebio-Construction, en construisant selon le principe du monomur (Blocs + enduit int\u00e9rieur + enduit ext\u00e9rieur), la mise en oeuvre est plus simple et plus rapide et les erreurs d\u2019ex\u00e9cution sont \u00e9limin\u00e9es. Les co\u00fbts et les d\u00e9lais de construction sont r\u00e9duit significativement et les ma\u00eetres d\u2019oeuvre profitent de meilleures conditions de travail sur chantier.Enfin, les solutions ENERGIEBLOC et PASSIFBLOC offrent des constructions monomur saines pour les habitants et assurent un confort thermique optimal comme l\u2019a constat\u00e9 Mr Turpin, habitant d\u2019une maison passive en Cellumat monomur.<\/p>\n\n\n\n<h2>CONSTRUIRE EN MONOMUR AVEC LE B\u00c9TON CELLULAIRE CELLUMAT \u00abTOUT EN UN\u00bb<\/h2>\n\n\n\n<p style=\"text-align:justify\"><strong>Porteur, isolant et \u00e9tanche \u00e0 l\u2019air<\/strong><br> En monomur, les solutions ENERGIEBLOC et PASSIFBLOC sont jusqu\u2019\u00e0 5 fois plus isolants que d\u2019autres mat\u00e9riaux porteurs isolants. Ils assurent des constructions de murs avec une r\u00e9sistance thermique R jusqu\u2019\u00e0 7,88 m2K\/W gr\u00e2ce \u00e0 leur conductivit\u00e9 thermique lambda de 0,09 W\/mK (ENERGIEBLOC) et de 0,065 W\/mK (PASSIFBLOC), sans mat\u00e9riau d\u2019isolation suppl\u00e9mentaire ni de rubans, enduits d\u2019\u00e9tanch\u00e9it\u00e9\u2026<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" width=\"301\" height=\"254\" src=\"https:\/\/i1.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2019\/09\/cellumat10.jpg?resize=301%2C254\" alt=\"\" class=\"wp-image-2657\" srcset=\"https:\/\/i1.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2019\/09\/cellumat10.jpg?w=301 301w, https:\/\/i1.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2019\/09\/cellumat10.jpg?resize=300%2C253 300w, https:\/\/i1.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2019\/09\/cellumat10.jpg?resize=10%2C8 10w, https:\/\/i1.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2019\/09\/cellumat10.jpg?resize=261%2C220 261w\" sizes=\"(max-width: 600px) 91vw, (max-width: 900px) 600px, (max-width: 1060px) 50vw, (max-width: 1200px) 520px, (max-width: 1400px) 43vw, 600px\" data-recalc-dims=\"1\" \/><figcaption>Stanislas Della Valle, architecte de L\u2019Atelier d\u2019Architecture Della Valle, t\u00e9moigne :<\/figcaption><\/figure><\/div>\n\n\n\n<blockquote class=\"wp-block-quote\"><p>\u00ab Je propose souvent aux propri\u00e9taires des constructions monomur  Cellumat en b\u00e9ton cellulaire. Leur conception et leur mise en oeuvre est  plus facile. Tr\u00e8s bon porteur, ce mat\u00e9riau permet d\u2019avoir des murs  hydrophobes, avec un bon comportement thermique et un tr\u00e8s bon  d\u00e9phasage. Les blocs Cellumat sont \u00e0 la fois \u00e9tanches \u00e0 l\u2019air, tr\u00e8s  perspirants, et pr\u00e9sentent \u00e9galement l\u2019avantage d\u2019apporter un bon  confort acoustique en 36,5 cm.<br> Par ailleurs, ils offrent un grand confort de mise en oeuvre avec la possibilit\u00e9 de reprises et\/ou de modifications ais\u00e9es. Ils permettent de r\u00e9aliser des murs courbes tr\u00e8s facilement et de cr\u00e9er ainsi des b\u00e2timents plus g\u00e9n\u00e9reux et plus doux. De plus, la r\u00e9alisation des noeuds constructifs est plus simple avec des blocs en b\u00e9ton cellulaire de 36,5 cm d\u2019\u00e9paisseur minimum, car il n\u2019y a pas de pont thermique.<br> Enfin, l\u2019execution est plus rapide et all\u00e9g\u00e9e pour les ouvriers car les temps de pose sont raccourcis, et les chantiers sont tr\u00e8s propres. \u00bb<\/p><\/blockquote>\n\n\n\n<p><strong>Porteurs et isolants, les solutions b\u00e9ton cellulaire sont naturellement 100 % \u00e9tanches \u00e0 l\u2019air, avec des valeurs allant jusqu\u2019\u00e0 0,0009 m3\/h.m2, et le restent pendant toute leur dur\u00e9e de vie<\/strong>. M\u00eame si l\u2019on fore dans les blocs ou que l\u2019on r\u00e9alise des saign\u00e9es pour les conduites techniques, l\u2019\u00e9tanch\u00e9it\u00e9 ou l\u2019isolation du mur n\u2019est pas affect\u00e9e<\/p>\n\n\n\n<blockquote class=\"wp-block-quote\"><p>Clotilde DHENNIN, Architecte \u00e0 l\u2019agence KAIZEN ARCHITECTURE le confirme :<br> \u00ab De notre point de vue, la r\u00e9alisation de saign\u00e9es pour le passage des r\u00e9seaux est plus simple \u00e0 traiter avec le b\u00e9ton cellulaire, qu\u2019avec la brique, notamment sur les questions de l\u2019\u00e9tanch\u00e9it\u00e9 \u00e0 l\u2019air et du confort phonique. \u00bb<\/p><\/blockquote>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"650\" height=\"532\" src=\"https:\/\/i0.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2019\/09\/cellumat7.jpg?resize=650%2C532\" alt=\"\" class=\"wp-image-2658\" srcset=\"https:\/\/i0.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2019\/09\/cellumat7.jpg?w=650 650w, https:\/\/i0.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2019\/09\/cellumat7.jpg?resize=300%2C246 300w, https:\/\/i0.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2019\/09\/cellumat7.jpg?resize=10%2C8 10w, https:\/\/i0.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2019\/09\/cellumat7.jpg?resize=432%2C354 432w, https:\/\/i0.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2019\/09\/cellumat7.jpg?resize=396%2C324 396w, https:\/\/i0.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2019\/09\/cellumat7.jpg?resize=269%2C220 269w\" sizes=\"(max-width: 600px) 91vw, (max-width: 900px) 600px, (max-width: 1060px) 50vw, (max-width: 1200px) 520px, (max-width: 1400px) 43vw, 600px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<p><strong>Une mise en oeuvre simple et rapide<\/strong><br> La construction en monomur Cellumat, sans mat\u00e9riau d\u2019isolation, sans membrane et sans ruban d\u2019\u00e9tanch\u00e9it\u00e9, mais avec un seul mat\u00e9riau, permet de r\u00e9aliser un mur complet et de r\u00e9duire consid\u00e9rablement les manipulations et les risques d\u2019erreurs d\u2019ex\u00e9cution. Ce mode constructif :<\/p>\n\n\n\n<ul><li>Evite les probl\u00e8mes rencontr\u00e9s li\u00e9s \u00e0 la pose d\u2019isolants, co\u00fbteuse et d\u00e9licate. Des isolants comprim\u00e9s avec des \u00e9carts aux jointures sont souvent la cause de condensation et de moisissures, de fuites d\u2019air et de ponts thermiques.<\/li><li>Elimine les erreurs d\u2019ex\u00e9cution au niveau des noeuds constructifs, qui peuvent avoir une incidence sur les pertes de chaleur de l\u2019habitation. La conception des noeuds constructifs avec des \u00e9l\u00e9ments en b\u00e9ton cellulaire (blocs U pour l\u2019all\u00e8ge, blocs perc\u00e9s pour l\u2019int\u00e9gration de colonnes structurelles dans la ma\u00e7onnerie\u2026) est simple, sans ponts thermiques, et permet d\u2019atteindre automatiquement des valeurs psi et des facteurs de temp\u00e9rature in\u00e9gal\u00e9s.<\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" width=\"268\" height=\"318\" src=\"https:\/\/i2.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2019\/09\/cellumat11.jpg?resize=268%2C318\" alt=\"\" class=\"wp-image-2659\" srcset=\"https:\/\/i2.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2019\/09\/cellumat11.jpg?w=268 268w, https:\/\/i2.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2019\/09\/cellumat11.jpg?resize=253%2C300 253w, https:\/\/i2.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2019\/09\/cellumat11.jpg?resize=8%2C10 8w, https:\/\/i2.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2019\/09\/cellumat11.jpg?resize=185%2C220 185w\" sizes=\"(max-width: 600px) 91vw, (max-width: 900px) 600px, (max-width: 1060px) 50vw, (max-width: 1200px) 520px, (max-width: 1400px) 43vw, 600px\" data-recalc-dims=\"1\" \/><figcaption>Thierry Giambelluco, g\u00e9rant de Bebio-Construction et conseiller Maison passive certifi\u00e9, nous explique :<\/figcaption><\/figure><\/div>\n\n\n\n<blockquote class=\"wp-block-quote\"><p>\u00ab Le grand avantage du PASSIFBLOC, c\u2019est sa bonne inertie thermique et le recours \u00e0 un seul intervenant : en une seule op\u00e9ration lors de la mise en oeuvre, on r\u00e9alise la structure et l\u2019isolation. Les murs ne n\u00e9cessitent pas d\u2019isolants compl\u00e9mentaires, ni de vide technique.<br> Zoom sur des noeuds constructifs<br> Par ailleurs, il s\u2019agit d\u2019un mat\u00e9riau plein, ce qui contribue \u00e0 l\u2019obtention d\u2019un bon test d\u2019\u00e9tanch\u00e9it\u00e9, qui, de plus, est p\u00e9renne. Le test d\u2019infiltrom\u00e9trie interm\u00e9diaire, r\u00e9alis\u00e9 avant les pl\u00e2tres et les enduits, confirme l\u2019efficacit\u00e9 du b\u00e9ton cellulaire en termes d\u2019\u00e9tanch\u00e9it\u00e9 \u00e0 l\u2019air. \u00bb<\/p><\/blockquote>\n\n\n\n<p>En monomur, les solutions Cellumat permettent une ex\u00e9cution beaucoup plus rapide qu\u2019avec d\u2019autres syst\u00e8mes constructifs, surtout au niveau des noeuds constructifs, car ils se collent \u00e0 l\u2019aide d\u2019un joint extr\u00eamement fin de quelques millim\u00e8tres.<br>\nPar ailleurs, les solutions ENERGIEBLOC et PASSIFBLOC sont l\u00e9gers, ergonomiques, faciles \u00e0 rainurer et \u00e0 d\u00e9couper aux dimensions souhait\u00e9es, ce qui simplifie leur mise en oeuvre. Plus faciles \u00e0 scier, ils peuvent prendre toutes les formes.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote\"><p>Thierry Giambelluco confirme :<br> \u00ab Finalement en construisant en monomur, on gagne en temps et en qualit\u00e9, et donc en prix compar\u00e9 \u00e0 une solution en parpaings conventionnels \u00e0 performance \u00e9gale \u00bb.<\/p><\/blockquote>\n\n\n\n<h2>Des constructions saines et s\u00e9curis\u00e9es<\/h2>\n\n\n\n<p style=\"text-align:justify\"> Certifi\u00e9s A+, les solutions ENERGIEBLOC et PASSIFBLOC ne g\u00e9n\u00e8rent aucun polluant ni particules dans l\u2019air. Compos\u00e9 d\u2019un minimum de mati\u00e8res premi\u00e8res et fabriqu\u00e9 avec un minimum d\u2019\u00e9nergie, les solutions constructives en b\u00e9ton cellulaire Celllumat ont une faible empreinte \u00e9cologique.<br> De plus, les ma\u00e7onneries r\u00e9alis\u00e9es en ENERGIEBLOC et PASSIFBLOC sont dites respirantes car les blocs en b\u00e9ton cellulaire sont constitu\u00e9s de cellules ferm\u00e9es pourvues de pores nanoscopiques, perm\u00e9ables \u00e0 la vapeur. Ils r\u00e9gulent les \u00e9changes gazeux et l\u2019humidit\u00e9 entre les atmosph\u00e8res int\u00e9rieures et ext\u00e9rieures, et \u00e9liminent le risque de condensation ou de moisissures.<br> Par ailleurs, la structure des blocs en b\u00e9ton cellulaire ENERGIEBLOC et PASSIFBLOC assure un confort d\u2019\u00e9t\u00e9 optimale en maintenant, tout au long de l\u2019ann\u00e9e, une temp\u00e9rature constante \u00e0 l\u2019int\u00e9rieur, quels que soient les \u00e9carts de temp\u00e9rature ext\u00e9rieure.<br> Gr\u00e2ce \u00e0 l\u2019inertie thermique des blocs, la chaleur s\u2019accumule dans les murs. Le d\u00e9phasage du mat\u00e9riau fait en sorte que cette chaleur ne soit transmise que graduellement vers l\u2019int\u00e9rieur, \u00e9vitant ainsi la surchauffe. La temp\u00e9rature dans la maison reste donc toujours agr\u00e9able et fra\u00eeche.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote\"><p>Mr Turpin \u2013 Habitant d\u2019une maison passive  en monomur Cellumat dans le Vaucluse<br> \u00ab Cela fait maintenant 2 ans que nous vivons dans notre maison passive monomur Cellumat. Situ\u00e9e dans le Vaucluse, la maison a \u00e9t\u00e9 orient\u00e9e plein sud pour que nous puissions profiter d\u2019un bon ensoleillement. La conception de la maison offre un excellent confort thermique et n\u2019a pas n\u00e9cessit\u00e9 l\u2019installation d\u2019un chauffage car elle est bien isol\u00e9e gr\u00e2ce aux murs en b\u00e9ton cellulaire en PASSIFBLOC de 40 cm d\u2019\u00e9paisseur, bien \u00e9quip\u00e9e avec une VMC double flux, de grandes baies avec un triple vitrage\u2026<br> Depuis que nous sommes install\u00e9s, nous n\u2019avons pas souffert de la chaleur l\u2019\u00e9t\u00e9, malgr\u00e9 une p\u00e9riode caniculaire. Il faisait environ 26\u00b0C dans la maison pendant la p\u00e9riode la plus chaude. En p\u00e9riode hivernale, nous avons une temp\u00e9rature int\u00e9rieure de 21 \u00e0 24\u00b0C selon les heures d\u2019ensoleillement.<br> Il est tr\u00e8s agr\u00e9able de vivre dans cette maison o\u00f9 l\u2019air est \u00ab sain \u00bb et les mat\u00e9riaux polluants r\u00e9duits au maximum (notamment pour les peintures, les enduits\u2026). Au quotidien, on respire bien et on s\u2019y sent vraiment bien. \u00bb<\/p><\/blockquote>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"607\" height=\"697\" src=\"https:\/\/i0.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2019\/09\/cellumat9.jpg?resize=607%2C697\" alt=\"\" class=\"wp-image-2660\" srcset=\"https:\/\/i0.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2019\/09\/cellumat9.jpg?w=607 607w, https:\/\/i0.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2019\/09\/cellumat9.jpg?resize=261%2C300 261w, https:\/\/i0.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2019\/09\/cellumat9.jpg?resize=10%2C10 10w, https:\/\/i0.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2019\/09\/cellumat9.jpg?resize=432%2C496 432w, https:\/\/i0.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2019\/09\/cellumat9.jpg?resize=396%2C455 396w, https:\/\/i0.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2019\/09\/cellumat9.jpg?resize=192%2C220 192w\" sizes=\"(max-width: 600px) 91vw, (max-width: 900px) 600px, (max-width: 1060px) 50vw, (max-width: 1200px) 520px, (max-width: 1400px) 43vw, 600px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<p>De classe Europ\u00e9enne A1, le b\u00e9ton cellulaire est incombustible et ininflammable. Ces propri\u00e9t\u00e9s antifeu uniques r\u00e9sultent de la structure en cellules ferm\u00e9es qui limite l\u2019extension de l\u2019incendie et l\u2019\u00e9l\u00e9vation de temp\u00e9rature dans les locaux adjacents.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MONOMUR EN B\u00c9TON CELLULAIRE : DES CONSTRUCTIONS PARFAITEMENT \u00c9TANCHES \u00c0 L\u2019AIR, FACILES \u00c0 METTRE EN OEUVRE ET SANS ISOLANTS RAPPORT\u00c9S Le b\u00e9ton cellulaire apporte une v\u00e9ritable solution monomur. En construisant avec les solutions Cellumat monomur, on r\u00e9pond de fa\u00e7on simple et \u00e9conomique aux crit\u00e8res thermiques de la RT et m\u00eame de la norme passive.Comme le [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2661,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":""},"categories":[21,29,486,77,80,128],"tags":[168,503],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2019\/09\/cellumat13_image.jpg?fit=1119%2C748","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":22283,"url":"http:\/\/batimedianews.com\/live\/index.php\/2022\/08\/03\/construire-malin-avec-le-beton-cellulaire-ytong\/","url_meta":{"origin":2656,"position":0},"title":"Construire malin avec le b\u00e9ton cellulaire Ytong","date":"3 ao\u00fbt 2022","format":false,"excerpt":"\u00a0La solution de construction anti-crise face \u00e0 l\u2019envol\u00e9e\u00a0des co\u00fbts \u00e9nerg\u00e9tiques et de production Avec l\u2019entr\u00e9e en vigueur de la RE2020, les p\u00e9nuries rencontr\u00e9es par certains fabricants, la hausse des prix des mat\u00e9riaux de construction et des co\u00fbts \u00e9nerg\u00e9tiques, de nombreux acteurs de la construction cherchent des solutions qui permettent de\u2026","rel":"","context":"Dans &quot;Actualit\u00e9 Entreprises&quot;","img":{"alt_text":"","src":"https:\/\/i2.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2022\/07\/Xella-Article.jpg?fit=1080%2C1080&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":45007,"url":"http:\/\/batimedianews.com\/live\/index.php\/2025\/05\/21\/dalles-en-beton-cellulaire-grand-format-hebel-la-solution-economique-pour-les-projets-de-construction-et-dextension-de-batiments-tertiaires-et-industriels\/","url_meta":{"origin":2656,"position":1},"title":"DALLES EN B\u00c9TON CELLULAIRE GRAND FORMAT HEBEL &#8211; La solution \u00e9conomique pour les projets de construction et d\u2019extension de b\u00e2timents tertiaires et industriels","date":"21 mai 2025","format":false,"excerpt":"R\u00e9pondre aux exigences incendie tout en ma\u00eetrisant les co\u00fbts de construction, telle est la raison d\u2019\u00eatre des dalles pr\u00e9fabriqu\u00e9es arm\u00e9es en b\u00e9ton cellulaire Hebel. Avec ce syst\u00e8me constructif grand format, Xella simplifie la conception de chantiers XXL, l'extension de b\u00e2timents industriels et utilitaires - plateformes logistiques, entrep\u00f4ts, sites de production,\u2026","rel":"","context":"Dans &quot;Actualit\u00e9 Entreprises&quot;","img":{"alt_text":"","src":"https:\/\/i2.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2025\/05\/Xella.jpg?fit=825%2C825&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":23878,"url":"http:\/\/batimedianews.com\/live\/index.php\/2022\/10\/02\/nouveau-bloc-en-beton-cellulaire-ytong-compact-15\/","url_meta":{"origin":2656,"position":2},"title":"Nouveau bloc en b\u00e9ton cellulaire Ytong Compact 15","date":"2 octobre 2022","format":false,"excerpt":"\u00a0Le mur isolant le moins \u00e9pais du march\u00e9 ! \u00a0Pour relever le d\u00e9fi de la r\u00e9glementation RE2020 et apporter le meilleur rapport qualit\u00e9 \/ prix \/ performances thermiques et \u00e9nerg\u00e9tiques, Xella lance sur le march\u00e9 le nouveau bloc en b\u00e9ton cellulaire Ytong Compact 15. D\u00e9di\u00e9e \u00e0 la construction de maisons\u2026","rel":"","context":"Dans &quot;Actualit\u00e9 Entreprises&quot;","img":{"alt_text":"","src":"https:\/\/i2.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2022\/10\/Xella-Article.jpg?fit=1080%2C1080&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":7830,"url":"http:\/\/batimedianews.com\/live\/index.php\/2021\/01\/19\/solution-maison-passive\/","url_meta":{"origin":2656,"position":3},"title":"Solution maison passive","date":"19 janvier 2021","format":false,"excerpt":"\u00a0Des maisons passives\u00a0en Ytong Energie au sein\u00a0du plus grand \u00e9coquartier\u00a0de France \u00e0 Carquefou\u00a0 Situ\u00e9e en proche p\u00e9riph\u00e9rie de Nantes, la ville de Carquefou (44) accueille l\u2019\u00e9coquartier de La Fleuriaye. Avec de nombreux b\u00e2timents associant du collectif \u00e0 de la maison individuelle, un Institut m\u00e9dico-\u00e9ducatif (IME), un centre \u00e9questre et 5\u2026","rel":"","context":"Dans &quot;Actualit\u00e9 Entreprises&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2021\/01\/image-111.png?fit=558%2C464&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":10119,"url":"http:\/\/batimedianews.com\/live\/index.php\/2021\/05\/26\/un-projet-de-maison-individuelle-decouvrez-le-nouveau-site-internet-ytong-inside\/","url_meta":{"origin":2656,"position":4},"title":"Un projet de maison individuelle ? D\u00e9couvrez le nouveau site internet Ytong Inside","date":"26 mai 2021","format":false,"excerpt":"\u00a0Ytong Inside, tout savoir sur le b\u00e9ton cellulaire\u00a0pour construire une maison confortable, durable et performante En 2021, la sensibilisation des particuliers aux solutions constructives en b\u00e9ton cellulaire Ytong pour leur projet de maison individuelle prend une nouvelle dimension avec l\u2019arriv\u00e9e du site ytong-inside.fr. \u00a0Les enjeux environnementaux ont contribu\u00e9 \u00e0 faire\u2026","rel":"","context":"Dans &quot;Actualit\u00e9 Entreprises&quot;","img":{"alt_text":"","src":"https:\/\/i2.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2021\/05\/Ytong-Article.jpg?fit=512%2C512&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":21494,"url":"http:\/\/batimedianews.com\/live\/index.php\/2022\/07\/04\/rehabilitation-du-quartier-baltiss-a-voiron-38\/","url_meta":{"origin":2656,"position":5},"title":"R\u00e9habilitation du quartier Baltiss \u00e0 Voiron (38)","date":"4 juillet 2022","format":false,"excerpt":"5 b\u00e2timents font peau neuve avec du b\u00e9ton cellulaire Ytong, une solution constructive parfaite\u00a0pour la r\u00e9novation \u00e9nerg\u00e9tique La loi \u00e9nergie-climat, qui fixe l\u2019objectif de neutralit\u00e9 carbone des b\u00e2timents d\u2019ici 2050, acc\u00e9l\u00e8re la r\u00e9novation des logements \u00e9nergivores en France. De nombreuses communes, comme Voiron dans l\u2019Is\u00e8re, engagent des travaux de r\u00e9habilitation\u2026","rel":"","context":"Dans &quot;Actualit\u00e9 Entreprises&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2022\/06\/Xella-Article.jpg?fit=1080%2C1080&resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"http:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/posts\/2656"}],"collection":[{"href":"http:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/comments?post=2656"}],"version-history":[{"count":1,"href":"http:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/posts\/2656\/revisions"}],"predecessor-version":[{"id":2662,"href":"http:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/posts\/2656\/revisions\/2662"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/media\/2661"}],"wp:attachment":[{"href":"http:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/media?parent=2656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/categories?post=2656"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/tags?post=2656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}