{"id":40549,"date":"2024-10-16T11:47:18","date_gmt":"2024-10-16T09:47:18","guid":{"rendered":"http:\/\/batimedianews.com\/live\/?p=40549"},"modified":"2025-04-08T20:10:36","modified_gmt":"2025-04-08T18:10:36","slug":"les-premiers-prototypes-de-van-ea-prennent-la-route","status":"publish","type":"post","link":"https:\/\/batimedianews.com\/live\/index.php\/2024\/10\/16\/les-premiers-prototypes-de-van-ea-prennent-la-route\/","title":{"rendered":"Les premiers prototypes de VAN.EA prennent la route"},"content":{"rendered":"\n<p>&nbsp;Stuttgart \/ Montigny le Bretonneux (78). Mercedes Benz Vans met en oeuvre la prochaine \u00e9tape de sa strat\u00e9gie d\u2019\u00e9lectrification avec VAN. EA. \u00c0 partir de 2026, tous les nouveaux fourgons moyens et grands d\u00e9velopp\u00e9s par Mercedes-Benz seront bas\u00e9s sur l\u2019architecture \u00e9lectrique modulaire, flexible et \u00e9volutive VAN. EA (Mercedes-Benz Van Electric Architecture). Les premiers prototypes de VAN.EA sont maintenant sur la voie publique, une \u00e9tape importante sur la voie de la r\u00e9invention du Van et du VUL par Mercedes-Benz.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" width=\"720\" height=\"480\" src=\"https:\/\/i2.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2024\/10\/image-244.png?resize=720%2C480\" alt=\"\" class=\"wp-image-40550\" srcset=\"https:\/\/i2.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2024\/10\/image-244.png?w=1450&amp;ssl=1 1450w, https:\/\/i2.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2024\/10\/image-244.png?resize=768%2C511&amp;ssl=1 768w, https:\/\/i2.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2024\/10\/image-244.png?resize=432%2C288&amp;ssl=1 432w, https:\/\/i2.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2024\/10\/image-244.png?resize=396%2C264&amp;ssl=1 396w, https:\/\/i2.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2024\/10\/image-244.png?resize=1120%2C746&amp;ssl=1 1120w, https:\/\/i2.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2024\/10\/image-244.png?resize=660%2C440&amp;ssl=1 660w\" sizes=\"(max-width: 600px) 91vw, (max-width: 900px) 600px, (max-width: 1060px) 50vw, (max-width: 1200px) 520px, (max-width: 1400px) 43vw, 600px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<p>&nbsp;VAN. EA permet de diff\u00e9rencier clairement les navettes priv\u00e9es dans le segment de luxe des utilitaires premium. Concernant les vans priv\u00e9s, le portefeuille ira <strong>des vans familiales aux navettes VIP exclusives en passant par les limousines luxueuses et spacieuses<\/strong> pour les clients les plus exigeants.&nbsp;<\/p>\n\n\n\n<p>En ce qui concerne les technologies install\u00e9es, les nouveaux vans r\u00e9pondront \u00e0 une grande vari\u00e9t\u00e9 de demandes. Qu\u2019ils soient en version traction ou \u00e0 quatre roues motrices, tous seront \u00e9quip\u00e9s de la derni\u00e8re version du syst\u00e8me d\u2019exploitation Mercedes-Benz (<strong>MB. OS<\/strong>), d\u2019un syst\u00e8me de <strong>charge de 800<\/strong> <strong>volts<\/strong> et d\u2019un <strong>chargeur AC de 22 kW<\/strong>.&nbsp;<\/p>\n\n\n\n<p>Apr\u00e8s un long essai de d\u00e9veloppement (plus de 3 000 km) de Stuttgart jusqu\u2019au Cap Nord (Norv\u00e8ge) d\u00e9but juin avec un v\u00e9hicule sp\u00e9cialement con\u00e7u pour tester le ch\u00e2ssis, le groupe motopropulseur \u00e9lectrique, la batterie et les composants haute tension, les tests actuels se concentrent sur l\u2019interaction de tous les composants dans l\u2019ensemble du v\u00e9hicule. En hiver,<strong> la prochaine \u00e9tape importante sera les essais \u00e0 froid en Su\u00e8de<\/strong>.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" width=\"720\" height=\"478\" src=\"https:\/\/i2.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2024\/10\/image-245.png?resize=720%2C478\" alt=\"\" class=\"wp-image-40551\" srcset=\"https:\/\/i2.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2024\/10\/image-245.png?w=1506&amp;ssl=1 1506w, https:\/\/i2.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2024\/10\/image-245.png?resize=768%2C509&amp;ssl=1 768w, https:\/\/i2.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2024\/10\/image-245.png?resize=432%2C287&amp;ssl=1 432w, https:\/\/i2.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2024\/10\/image-245.png?resize=396%2C263&amp;ssl=1 396w, https:\/\/i2.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2024\/10\/image-245.png?resize=1120%2C744&amp;ssl=1 1120w, https:\/\/i2.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2024\/10\/image-245.png?resize=660%2C438&amp;ssl=1 660w, https:\/\/i2.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2024\/10\/image-245.png?w=1440 1440w\" sizes=\"(max-width: 600px) 91vw, (max-width: 900px) 600px, (max-width: 1060px) 50vw, (max-width: 1200px) 520px, (max-width: 1400px) 43vw, 600px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;Stuttgart \/ Montigny le Bretonneux (78). Mercedes Benz Vans met en oeuvre la prochaine \u00e9tape de sa strat\u00e9gie d\u2019\u00e9lectrification avec VAN. EA. \u00c0 partir de 2026, tous les nouveaux fourgons moyens et grands d\u00e9velopp\u00e9s par Mercedes-Benz seront bas\u00e9s sur l\u2019architecture \u00e9lectrique modulaire, flexible et \u00e9volutive VAN. EA (Mercedes-Benz Van Electric Architecture). Les premiers prototypes de [&hellip;]<\/p>\n","protected":false},"author":41,"featured_media":40552,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":""},"categories":[4,132],"tags":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2024\/10\/Mercedes.jpg?fit=1513%2C825&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":35621,"url":"https:\/\/batimedianews.com\/live\/index.php\/2024\/02\/27\/conference-de-presse-resultats-2023-mercedes-benz-group-focus-vans\/","url_meta":{"origin":40549,"position":0},"title":"Conf\u00e9rence de presse \u00ab R\u00e9sultats 2023 Mercedes-Benz Group \u00bb : focus Vans","date":"27 f\u00e9vrier 2024","format":false,"excerpt":"\u00a0En 2023, le chiffre d\u2019affaires de Mercedes-Benz Vans a atteint 20,3 milliards d\u2019euros (+18%) pour un EBIT (b\u00e9n\u00e9fice avant int\u00e9r\u00eats et imp\u00f4ts) de 3,1 milliards d\u2019euros (+59%). Les ventes marquent un nouveau record sur chaque segment et au global, atteignant 447 800 unit\u00e9s (+ 8% vs 2022 : 415 300\u2026","rel":"","context":"Dans &quot;Actualit\u00e9 Entreprises&quot;","img":{"alt_text":"","src":"https:\/\/i1.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2024\/02\/image-266.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":49495,"url":"https:\/\/batimedianews.com\/live\/index.php\/2026\/03\/04\/pourquoi-de-plus-en-plus-dartisans-choisissent-un-utilitaire-mercedes\/","url_meta":{"origin":40549,"position":1},"title":"Pourquoi de plus en plus d\u2019artisans choisissent un utilitaire Mercedes ?","date":"4 mars 2026","format":false,"excerpt":"Fiabilit\u00e9, s\u00e9curit\u00e9 et confort : l\u2019utilitaire devient un v\u00e9ritable outil de travail pour les professionnels du b\u00e2timent Pour les artisans et entreprises du b\u00e2timent, le v\u00e9hicule utilitaire est bien plus qu\u2019un simple moyen de transport. Il est \u00e0 la fois atelier mobile, espace de stockage et outil de travail quotidien.\u2026","rel":"","context":"Dans &quot;Outils connect\u00e9s&quot;","img":{"alt_text":"","src":"https:\/\/i2.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2026\/03\/lMercedes_Image_Article-1.png?fit=1169%2C638&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":37328,"url":"https:\/\/batimedianews.com\/live\/index.php\/2024\/05\/16\/reseau-mercedes-benz-vans-4-nouveaux-sites-pionniers\/","url_meta":{"origin":40549,"position":2},"title":"R\u00e9seau Mercedes-Benz Vans &#8211; 4 nouveaux sites pionniers","date":"16 mai 2024","format":false,"excerpt":"\u00a0Montigny-le-Bretonneux (78) En France, quatre nouveaux \u00e9tablissements ont r\u00e9cemment \u00e9t\u00e9 inaugur\u00e9s dans le r\u00e9seau Mercedes-Benz Utilitaires. Ils r\u00e9pondent aux derniers standards \u2013 baptis\u00e9s \u00ab MAR20X* \u00bb de la marque afin de proposer aux professionnels un parcours client VN et SAV toujours plus premium, au b\u00e9n\u00e9fice de leur efficacit\u00e9.\u00a0 \u00a0Le r\u00e9seau\u2026","rel":"","context":"Dans &quot;Actualit\u00e9 Entreprises&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2024\/05\/Mercedes.jpg?fit=825%2C825&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":39731,"url":"https:\/\/batimedianews.com\/live\/index.php\/2024\/09\/17\/jubiles-mercedes-benz-vans-des-decennies-dinnovation\/","url_meta":{"origin":40549,"position":3},"title":"Jubil\u00e9s Mercedes-Benz Vans: des d\u00e9cennies d\u2019innovation","date":"17 septembre 2024","format":false,"excerpt":"\u00a0Depuis des d\u00e9cennies, les utilitaires Mercedes sont des compagnons indispensables dans de nombreux secteurs. Des g\u00e9n\u00e9rations d\u2019artisans, de transporteurs de colis, de soci\u00e9t\u00e9s d\u2019ambulances et de passionn\u00e9s de camping-cars ont appr\u00e9ci\u00e9 les d\u00e9veloppements de ces v\u00e9hicules au fil des ans. Cette ann\u00e9e, la marque \u00e0 l\u2019\u00e9toile f\u00eate plusieurs anniversaires.\u00a0 \u2022\u2026","rel":"","context":"Dans &quot;Actualit\u00e9 Entreprises&quot;","img":{"alt_text":"","src":"https:\/\/i2.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2024\/09\/Mercedes.jpg?fit=825%2C825&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":14925,"url":"https:\/\/batimedianews.com\/live\/index.php\/2022\/01\/19\/la-capeb-et-mercedes-benz-france-sassocient-pour-permettre-aux-artisans-doptimiser-leur-outil-de-travail\/","url_meta":{"origin":40549,"position":4},"title":"La CAPEB et MERCEDES-BENZ France s&rsquo;associent pour permettre aux artisans d&rsquo;optimiser leur outil de travail","date":"19 janvier 2022","format":false,"excerpt":"Paris, le 13 janvier 2022 \u2013\u00a0LaConf\u00e9d\u00e9ration de l'Artisanat et des Petites Entreprises du B\u00e2timent\u00a0(CAPEB),\u00a0via sa filiale B\u00e9ranger D\u00e9veloppement, etMercedes-Benz France,\u00a0acteur majeur du march\u00e9 des utilitaires l\u00e9gers, ont sign\u00e9 un partenariat afin de r\u00e9f\u00e9rencer et de faciliter l'acc\u00e8s aux v\u00e9hicules de la marque aupr\u00e8s des entreprises artisanales du b\u00e2timent.\u00a0 De gauche\u2026","rel":"","context":"Dans &quot;b\u00e2timent&quot;","img":{"alt_text":"","src":"https:\/\/i1.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2022\/01\/CAPEB-Article-1.jpg?fit=512%2C512&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":38045,"url":"https:\/\/batimedianews.com\/live\/index.php\/2024\/06\/10\/le-ecitan-en-version-frigorifique\/","url_meta":{"origin":40549,"position":5},"title":"Le eCitan en version frigorifique","date":"10 juin 2024","format":false,"excerpt":"\u00a0La version 100% \u00e9lectrique du petit fourgon \u00e9toil\u00e9 se pr\u00eate parfaitement \u00e0 la transformation \u00ab v\u00e9hicule frigorifique \u00bb par trois carrossiers avec lesquels Mercedes-Benz Vans France travaille \u00e9troitement.\u00a0 \u00a0Environ un quart des Citan vendus sont am\u00e9nag\u00e9s ou passent chez un carrossier. Depuis d\u00e9but 2024, le eCitan, la version 100% \u00e9lectrique\u2026","rel":"","context":"Dans &quot;Actualit\u00e9 Entreprises&quot;","img":{"alt_text":"","src":"https:\/\/i1.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2024\/06\/Mercedes.jpg?fit=825%2C825&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/posts\/40549"}],"collection":[{"href":"https:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/comments?post=40549"}],"version-history":[{"count":2,"href":"https:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/posts\/40549\/revisions"}],"predecessor-version":[{"id":40780,"href":"https:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/posts\/40549\/revisions\/40780"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/media\/40552"}],"wp:attachment":[{"href":"https:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/media?parent=40549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/categories?post=40549"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/tags?post=40549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}