{"id":47695,"date":"2025-11-03T13:05:31","date_gmt":"2025-11-03T12:05:31","guid":{"rendered":"http:\/\/batimedianews.com\/live\/?p=47695"},"modified":"2025-11-03T13:05:34","modified_gmt":"2025-11-03T12:05:34","slug":"joncoux-devoile-deux-nouvelles-solutions-pour-repondre-aux-projets-industriels-et-tertiaires","status":"publish","type":"post","link":"https:\/\/batimedianews.com\/live\/index.php\/2025\/11\/03\/joncoux-devoile-deux-nouvelles-solutions-pour-repondre-aux-projets-industriels-et-tertiaires\/","title":{"rendered":"Joncoux d\u00e9voile deux nouvelles solutions pour r\u00e9pondre aux projets industriels et tertiaires"},"content":{"rendered":"\n<p class=\"has-text-align-justify\"><strong>Joncoux, concepteur-fabricant de conduits de fum\u00e9e et de ventilation depuis 1919, travaille en synergie avec les filiales du Groupe Sphering pour r\u00e9pondre aux demandes sp\u00e9cifiques. Pour mener \u00e0 bien ses projets industriels et tertiaires en France, la marque s&rsquo;appuie sur deux gammes innovantes d\u00e9velopp\u00e9es par MK, filiale polonaise du Groupe, sp\u00e9cialis\u00e9e dans la production de conduits industriels haute performance : <em>Europa <\/em>et <em>Kepler HPT<\/em>. Un choix strat\u00e9gique et des produits pr\u00e9sent\u00e9s sur le stand Joncoux lors du salon rennais Artibat, du 22 au 24 octobre 2025.<\/strong><\/p>\n\n\n\n<p class=\"has-text-color\" style=\"color:#5086c3\">&nbsp;<strong><em>Europa et Kepler HPT <\/em>: deux gammes adapt\u00e9es aux chantiers industriels et tertiaires.<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-justify\">Joncoux, concepteur-fabricant de conduits de fum\u00e9e et de ventilation depuis 1919, s\u2019impose comme un acteur incontournable du g\u00e9nie climatique en France. Pour maintenir cette dynamique et <strong>r\u00e9pondre aux demandes de chantiers industriels et tertiaires de grande ampleur, n\u00e9cessitant l\u2019installation de conduits sp\u00e9cifiques<\/strong>, la marque joue sur la compl\u00e9mentarit\u00e9 des expertises du Groupe Sphering. Joncoux s\u2019appuie ainsi sur <strong>MK, filiale polonaise du Groupe reconnue en Europe pour la qualit\u00e9, la pr\u00e9cision et la fiabilit\u00e9 de sa production de conduits industriels haute performance. <\/strong>Les gammes <em>Europa <\/em>et <em>Kepler HPT<\/em>, garanties 30 ans, en sont issues et constituent un savoir-faire de pointe.<\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide has-media-on-the-right is-stacked-on-mobile\" style=\"grid-template-columns:auto 28%\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" width=\"462\" height=\"380\" src=\"https:\/\/i0.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2025\/10\/image-194.png?resize=462%2C380\" alt=\"\" class=\"wp-image-47696 size-full\" srcset=\"https:\/\/i0.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2025\/10\/image-194.png?w=462&amp;ssl=1 462w, https:\/\/i0.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2025\/10\/image-194.png?resize=768%2C631&amp;ssl=1 768w, https:\/\/i0.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2025\/10\/image-194.png?resize=432%2C355&amp;ssl=1 432w, https:\/\/i0.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2025\/10\/image-194.png?resize=396%2C326&amp;ssl=1 396w\" sizes=\"(max-width: 600px) 91vw, (max-width: 900px) 600px, (max-width: 1060px) 50vw, (max-width: 1200px) 520px, (max-width: 1400px) 43vw, 600px\" data-recalc-dims=\"1\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-text-align-justify has-normal-font-size\">La <strong><em>gamme Europa <\/em><\/strong>s\u2019impose comme une solution de r\u00e9f\u00e9rence pour les installations exigeantes telles que les <strong>data centers, groupes \u00e9lectrog\u00e8nes, fours industriels, chaudi\u00e8res biomasse, r\u00e9seaux de chaleur, blanchisseries <\/strong>ou <strong>cuisines collectives. <\/strong>Elle est certifi\u00e9e <strong>EI180<\/strong>, garantissant une haute r\u00e9sistance au feu, capable de supporter une pression de <strong>15000 Pa<\/strong>, se maintient face \u00e0 l\u2019humidit\u00e9 comme au sec (<strong>T600<\/strong>) et se d\u00e9cline sous <strong>diff\u00e9rentes \u00e9paisseurs d&rsquo;isolant allant de 30 \u00e0 100 mm<\/strong>. Compatible avec une grande partie des normes internationales (<strong>CE, UKCA, UL et ULc<\/strong>), la gamme Europa est \u00e9galement facile \u00e0 installer gr\u00e2ce \u00e0 sa <strong>connexion \u00e0 flange, un joint en graphite et un embout centr\u00e9.<\/strong><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide has-media-on-the-right is-stacked-on-mobile\" style=\"grid-template-columns:auto 27%\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" width=\"462\" height=\"380\" src=\"https:\/\/i1.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2025\/10\/image-195.png?resize=462%2C380\" alt=\"\" class=\"wp-image-47697 size-full\" srcset=\"https:\/\/i1.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2025\/10\/image-195.png?w=462&amp;ssl=1 462w, https:\/\/i1.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2025\/10\/image-195.png?resize=768%2C631&amp;ssl=1 768w, https:\/\/i1.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2025\/10\/image-195.png?resize=432%2C355&amp;ssl=1 432w, https:\/\/i1.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2025\/10\/image-195.png?resize=396%2C326&amp;ssl=1 396w\" sizes=\"(max-width: 600px) 91vw, (max-width: 900px) 600px, (max-width: 1060px) 50vw, (max-width: 1200px) 520px, (max-width: 1400px) 43vw, 600px\" data-recalc-dims=\"1\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-text-align-justify has-normal-font-size\">La <strong><em>gamme Kepler HPT <\/em><\/strong>est un syst\u00e8me utilis\u00e9 comme <strong>conduit de fum\u00e9e ext\u00e9rieur autonome <\/strong>pour les <strong>groupes \u00e9lectrog\u00e8nes<\/strong>, les <strong>unit\u00e9s de cog\u00e9n\u00e9ration <\/strong>ainsi que pour d\u2019autres <strong>moteurs \u00e0 combustion interne <\/strong>et <strong>turbines<\/strong>. Sa caract\u00e9ristique principale est sa <strong>r\u00e9sistance \u00e0 une pression \u00e9lev\u00e9e, jusqu\u2019\u00e0 5000 Pa<\/strong>. Gr\u00e2ce aux raccords sp\u00e9ciaux des \u00e9l\u00e9ments sur l\u2019enveloppe, utilisant un silicone haute temp\u00e9rature ou en version avec joint et un <em>\u00ab noyau libre \u00bb <\/em>qui se dilate sous l\u2019effet des hautes temp\u00e9ratures, le syst\u00e8me remplit parfaitement sa fonction avec les groupes \u00e9lectrog\u00e8nes de tr\u00e8s grande puissance. Le syst\u00e8me ne n\u00e9cessite pas l\u2019utilisation de compensateurs de dilatation.<\/p>\n<\/div><\/div>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" width=\"720\" height=\"165\" src=\"https:\/\/i1.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2025\/10\/image-196.png?resize=720%2C165\" alt=\"\" class=\"wp-image-47698\" srcset=\"https:\/\/i1.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2025\/10\/image-196.png?w=1812&amp;ssl=1 1812w, https:\/\/i1.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2025\/10\/image-196.png?resize=768%2C176&amp;ssl=1 768w, https:\/\/i1.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2025\/10\/image-196.png?resize=432%2C99&amp;ssl=1 432w, https:\/\/i1.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2025\/10\/image-196.png?resize=396%2C91&amp;ssl=1 396w, https:\/\/i1.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2025\/10\/image-196.png?resize=1120%2C257&amp;ssl=1 1120w, https:\/\/i1.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2025\/10\/image-196.png?resize=660%2C152&amp;ssl=1 660w, https:\/\/i1.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2025\/10\/image-196.png?w=1440 1440w\" sizes=\"(max-width: 600px) 91vw, (max-width: 900px) 600px, (max-width: 1060px) 50vw, (max-width: 1200px) 520px, (max-width: 1400px) 43vw, 600px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<p><em>\u00ab <\/em><strong><em>Nous mettons un point d\u2019honneur \u00e0 travailler en synergie avec les marques du Groupe Sphering. <\/em><\/strong><em>En assemblant les diff\u00e9rents savoir-faire de pointe, nous garantissons \u00e0 nos clients une r\u00e9ponse parfaitement adapt\u00e9e. <\/em><strong><em>Chaque chantier devient une opportunit\u00e9 de croiser nos expertises. <\/em><\/strong><em>De cette mani\u00e8re, nous faisons rayonner Joncoux et plus encore \u00bb <\/em>souligne <strong>Ga\u00ebl Kauffmann<\/strong><em>, <\/em>directeur g\u00e9n\u00e9ral Joncoux.&nbsp;<\/p>\n\n\n\n<p class=\"has-text-color\" style=\"color:#5086c3\"><strong>Un troisi\u00e8me site de production bas carbone op\u00e9rationnel.&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-justify\">En avril 2024, Joncoux posait la premi\u00e8re pierre de son <strong>troisi\u00e8me site de production<\/strong>. Ce projet industriel phare&nbsp;int\u00e9gr\u00e9 au P\u00f4le d&rsquo;Excellence Industrielle de la Janais \u00e0 Chartres-de-Bretagne est aujourd&rsquo;hui op\u00e9rationnel. Le&nbsp;<strong>site de 8000 m<sup>2 <\/sup>accueille 74 collaborateurs <\/strong>ainsi que les activit\u00e9s de production et de peinture. <strong>Sa construction&nbsp;et son fonctionnement sont pens\u00e9s dans une logique bas carbone <\/strong>: des mat\u00e9riaux biosourc\u00e9s (ossature bois)&nbsp;\u00e0 la toiture \u00e9quip\u00e9e de panneaux photovolta\u00efques qui assurent 34% des besoins en \u00e9lectricit\u00e9 en passant par&nbsp;les espaces ext\u00e9rieurs v\u00e9g\u00e9talis\u00e9s. Les eaux pluviales sont r\u00e9cup\u00e9r\u00e9es et des pav\u00e9s drainants sont am\u00e9nag\u00e9s.&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-justify\"><strong>Une chaudi\u00e8re biomasse et un syst\u00e8me de ventilation double flux sign\u00e9s Joncoux sont install\u00e9s<\/strong>, garantissant&nbsp;un confort thermique et une qualit\u00e9 d&rsquo;air optimale.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" width=\"720\" height=\"160\" src=\"https:\/\/i0.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2025\/10\/image-197.png?resize=720%2C160\" alt=\"\" class=\"wp-image-47699\" srcset=\"https:\/\/i0.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2025\/10\/image-197.png?w=1812&amp;ssl=1 1812w, https:\/\/i0.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2025\/10\/image-197.png?resize=768%2C170&amp;ssl=1 768w, https:\/\/i0.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2025\/10\/image-197.png?resize=432%2C96&amp;ssl=1 432w, https:\/\/i0.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2025\/10\/image-197.png?resize=396%2C88&amp;ssl=1 396w, https:\/\/i0.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2025\/10\/image-197.png?resize=1120%2C248&amp;ssl=1 1120w, https:\/\/i0.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2025\/10\/image-197.png?resize=660%2C146&amp;ssl=1 660w, https:\/\/i0.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2025\/10\/image-197.png?w=1440 1440w\" sizes=\"(max-width: 600px) 91vw, (max-width: 900px) 600px, (max-width: 1060px) 50vw, (max-width: 1200px) 520px, (max-width: 1400px) 43vw, 600px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<p class=\"has-text-color\" style=\"color:#5086c3\"><strong>Une pr\u00e9sence sur le salon Artibat du 22 au 24 octobre.&nbsp;<\/strong><\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide has-media-on-the-right is-stacked-on-mobile\" style=\"grid-template-columns:auto 21%\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" width=\"430\" height=\"174\" src=\"https:\/\/i1.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2025\/10\/image-198.png?resize=430%2C174\" alt=\"\" class=\"wp-image-47700 size-full\" srcset=\"https:\/\/i1.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2025\/10\/image-198.png?w=430&amp;ssl=1 430w, https:\/\/i1.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2025\/10\/image-198.png?resize=768%2C310&amp;ssl=1 768w, https:\/\/i1.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2025\/10\/image-198.png?resize=396%2C160&amp;ssl=1 396w\" sizes=\"(max-width: 600px) 91vw, (max-width: 900px) 600px, (max-width: 1060px) 50vw, (max-width: 1200px) 520px, (max-width: 1400px) 43vw, 600px\" data-recalc-dims=\"1\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-text-align-justify\"><strong>Joncoux est pr\u00e9sent \u00e0 Artibat<\/strong>, le salon professionnel de la construction et&nbsp;des travaux publics du <strong>22 au 24 octobre 2025<\/strong>. L&rsquo;occasion pour la marque et&nbsp;ses \u00e9quipes de faire un point sur ses temps forts pass\u00e9s et futurs sur le <strong>stand&nbsp;B20, hall 7.&nbsp;<\/strong><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group has-background\" style=\"background-color:#e7e9ea\"><div class=\"wp-block-group__inner-container\">\n<p class=\"has-small-font-size\"><strong>\u00c0 propos de Joncoux&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-justify has-small-font-size\">Depuis 1919, Joncoux con\u00e7oit des conduits de fum\u00e9e et de ventilation garantis jusqu\u2019\u00e0 30 ans et destin\u00e9s aux professionnels. Son engagement pour la qualit\u00e9, sa politique d\u2019innovation constante et son savoir-faire expert, font de Joncoux une r\u00e9ussite industrielle \u00e0 la fran\u00e7aise. L\u2019entreprise compte actuellement 170 collaborateurs, 3 sites de fabrication en France (Rennes, Charleville-M\u00e9zi\u00e8res et Chartres-de-Bretagne). La marque s&rsquo;appuie aussi sur WeLab\u00ae, laboratoire consacr\u00e9 aux tests techniques de performance et de compatibilit\u00e9 des produits.&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-justify has-small-font-size\">L\u2019entreprise familiale centenaire fait partie du Groupe Sphering (sept marques), acteur de premier plan sur le march\u00e9 europ\u00e9en des conduits de fum\u00e9e et de ventilation.&nbsp;<\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Joncoux, concepteur-fabricant de conduits de fum\u00e9e et de ventilation depuis 1919, travaille en synergie avec les filiales du Groupe Sphering pour r\u00e9pondre aux demandes sp\u00e9cifiques. Pour mener \u00e0 bien ses projets industriels et tertiaires en France, la marque s&rsquo;appuie sur deux gammes innovantes d\u00e9velopp\u00e9es par MK, filiale polonaise du Groupe, sp\u00e9cialis\u00e9e dans la production de [&hellip;]<\/p>\n","protected":false},"author":41,"featured_media":47701,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"spay_email":""},"categories":[4,134],"tags":[2690],"jetpack_featured_media_url":"https:\/\/i2.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2025\/10\/Joncoux.jpg?fit=1513%2C825&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":40878,"url":"https:\/\/batimedianews.com\/live\/index.php\/2024\/10\/25\/joncoux-gagne-du-terrain-en-2024-une-annee-dinnovations-et-de-construction\/","url_meta":{"origin":47695,"position":0},"title":"Joncoux gagne du terrain en 2024 : une ann\u00e9e d\u2019innovations et de construction.","date":"25 octobre 2024","format":false,"excerpt":"\u00a0\u00c0 l'occasion du salon parisien Interclima qui s'est d\u00e9roul\u00e9 du 30 septembre au 3 octobre, Joncoux, concepteur-fabricant de conduits de fum\u00e9e et de ventilation depuis 1919 est revenu sur les temps forts 2023-2024. \u00c0 d\u00e9couvrir : Pegasus Flexishunt, un syst\u00e8me inox exclusif pour la r\u00e9novation des logements collectifs, et la\u2026","rel":"","context":"Dans &quot;Actualit\u00e9 Entreprises&quot;","img":{"alt_text":"","src":"https:\/\/i1.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2024\/10\/Joncoux-articles-.jpg?fit=825%2C825&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":38316,"url":"https:\/\/batimedianews.com\/live\/index.php\/2024\/06\/21\/joncoux-devoile-pegasus-flexishunt-le-seul-systeme-en-inox-dedie-a-la-renovation-des-logements-collectifs\/","url_meta":{"origin":47695,"position":1},"title":"Joncoux d\u00e9voile PEGASUS Flexishunt, le seul syst\u00e8me en inox d\u00e9di\u00e9 \u00e0 la r\u00e9novation des logements collectifs","date":"21 juin 2024","format":false,"excerpt":"Joncoux, concepteur et fabricant fran\u00e7ais de conduits de fum\u00e9e et de ventilation depuis 1919, d\u00e9voile sa nouvelle gamme Pegasus Flexishunt en juin 2024. Elle facilite l\u2019installation des chaudi\u00e8res \u00e0 gaz condensation de Tr\u00e8s Haute Performance \u00c9nerg\u00e9tique (THPE) sur des conduits Shunt et Alsace et assure l\u2019\u00e9vacuation des produits de combustion.\u2026","rel":"","context":"Dans &quot;Actualit\u00e9 Entreprises&quot;","img":{"alt_text":"","src":"https:\/\/i1.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2024\/06\/Joncoux-articles-.jpg?fit=825%2C825&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":22782,"url":"https:\/\/batimedianews.com\/live\/index.php\/2022\/09\/08\/ubbink-presente-ses-innovations-sur-les-salons-batimat-et-interclima-du-3-au-6-octobre-2022\/","url_meta":{"origin":47695,"position":2},"title":"Ubbink pr\u00e9sente ses innovations sur les salons Batimat et Interclima du 3 au 6 octobre 2022","date":"8 septembre 2022","format":false,"excerpt":"\u00a0Journ\u00e9e d\u00e9di\u00e9e \u00e0 la presse le Mardi 4 octobre 2022 sur le stand de Ubbink Pavillon 3 stand C094 \u00a0Ubbink, sp\u00e9cialiste de la performance \u00e9nerg\u00e9tique et du confort de l\u2019habitat, donne rendez-vous \u00e0 ses partenaires professionnels du b\u00e2timent sur ses deux stands distincts. \u00a0\u00c0 propos d\u2019Ubbink France Ubbink France, filiale\u2026","rel":"","context":"Dans &quot;Actualit\u00e9 Entreprises&quot;","img":{"alt_text":"","src":"https:\/\/i1.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2022\/09\/Ubbink-Article.jpg?fit=1080%2C1080&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":27242,"url":"https:\/\/batimedianews.com\/live\/index.php\/2023\/03\/22\/a-ish-2023-la-ventilation-cest-double-flux-ou-rien\/","url_meta":{"origin":47695,"position":3},"title":"A ISH 2023, la ventilation, c\u2019est double flux ou rien","date":"22 mars 2023","format":false,"excerpt":"Au salon ISH, les solutions de ventilation sont commercialis\u00e9es par toutes sortes d\u2019entreprises, les sp\u00e9cialistes, mais aussi les grands du chauffage et de la pompe \u00e0 chaleur. Premier constat \u00e0 propos de ventilation \u00e0 ISH, tout le monde en vend, ou presque. Bien s\u00fbr les sp\u00e9cialistes de la ventilation, de\u2026","rel":"","context":"Dans &quot;Actualit\u00e9 Entreprises&quot;","img":{"alt_text":"","src":"https:\/\/i1.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2023\/03\/Ish6image.jpeg?fit=1050%2C1050&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":22944,"url":"https:\/\/batimedianews.com\/live\/index.php\/2022\/09\/14\/avant-premiere-interclima-2022-rolux-multiflex-le-nouveau-systeme-de-renovation-pour-conduit-shunt-et-alsace\/","url_meta":{"origin":47695,"position":4},"title":"Avant premi\u00e8re INTERCLIMA 2022 : ROLUX MULTIFLEX, le nouveau syst\u00e8me de r\u00e9novation pour conduit Shunt et Alsace","date":"14 septembre 2022","format":false,"excerpt":"\u00c0 ce jour, le march\u00e9 du remplacement des chaudi\u00e8res est en forte croissance. L\u2019\u00e9volution des r\u00e9glementations impose un niveau de performance \u00e9nerg\u00e9tique et environnementale que seules les chaudi\u00e8res \u00e0 condensation peuvent atteindre. Cependant, les conduits ma\u00e7onn\u00e9s existants sont incompatibles avec les chaudi\u00e8res hautes performances condensation. Il convient alors de pr\u00e9voir\u2026","rel":"","context":"Dans &quot;Chauffage&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2022\/09\/ubbink-article-1.jpg?fit=1080%2C1080&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":49840,"url":"https:\/\/batimedianews.com\/live\/index.php\/2026\/03\/23\/linnovation-au-service-de-la-protection\/","url_meta":{"origin":47695,"position":5},"title":"L\u2019innovation au service de la protection","date":"23 mars 2026","format":false,"excerpt":"V\u00e9ritable expert sur le march\u00e9 de la protection incendie, France Air met \u00e0 la disposition des installateurs et des bureaux d\u2019\u00e9tudes son savoir-faire \u00e0 travers le lancement de plusieurs nouveaut\u00e9s en termes de mat\u00e9riel et de logiciel.\u00a0 Clapets coupe-feu CIRCE\u00ae 5 et REF 500\u00ae-5 : une installation facilit\u00e9e\u00a0 La protection\u2026","rel":"","context":"Dans &quot;Actualit\u00e9 Entreprises&quot;","img":{"alt_text":"","src":"https:\/\/i1.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2026\/03\/FranceAir.jpg?fit=825%2C825&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/posts\/47695"}],"collection":[{"href":"https:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/comments?post=47695"}],"version-history":[{"count":2,"href":"https:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/posts\/47695\/revisions"}],"predecessor-version":[{"id":47715,"href":"https:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/posts\/47695\/revisions\/47715"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/media\/47701"}],"wp:attachment":[{"href":"https:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/media?parent=47695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/categories?post=47695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/tags?post=47695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}