{"id":50598,"date":"2026-05-13T11:31:17","date_gmt":"2026-05-13T09:31:17","guid":{"rendered":"http:\/\/batimedianews.com\/live\/?p=50598"},"modified":"2026-05-13T11:31:20","modified_gmt":"2026-05-13T09:31:20","slug":"nouveau-vanlock-241-et-conhasp-205-abus-les-solutions-pour-securiser-les-equipements-sur-les-chantiers","status":"publish","type":"post","link":"https:\/\/batimedianews.com\/live\/index.php\/2026\/05\/13\/nouveau-vanlock-241-et-conhasp-205-abus-les-solutions-pour-securiser-les-equipements-sur-les-chantiers\/","title":{"rendered":"Nouveau : VANLOCK 241 et CONHASP 205 ABUS &#8211; Les solutions pour s\u00e9curiser les \u00e9quipements sur les chantiers"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" width=\"720\" height=\"400\" src=\"https:\/\/i0.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2026\/05\/image-71.png?resize=720%2C400\" alt=\"\" class=\"wp-image-50599\" srcset=\"https:\/\/i0.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2026\/05\/image-71.png?w=1816&amp;ssl=1 1816w, https:\/\/i0.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2026\/05\/image-71.png?resize=768%2C427&amp;ssl=1 768w, https:\/\/i0.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2026\/05\/image-71.png?resize=432%2C240&amp;ssl=1 432w, https:\/\/i0.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2026\/05\/image-71.png?resize=396%2C220&amp;ssl=1 396w, https:\/\/i0.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2026\/05\/image-71.png?resize=1120%2C623&amp;ssl=1 1120w, https:\/\/i0.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2026\/05\/image-71.png?resize=660%2C367&amp;ssl=1 660w, https:\/\/i0.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2026\/05\/image-71.png?w=1440 1440w\" sizes=\"(max-width: 600px) 91vw, (max-width: 900px) 600px, (max-width: 1060px) 50vw, (max-width: 1200px) 520px, (max-width: 1400px) 43vw, 600px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-justify\">Les vols de mat\u00e9riaux, mat\u00e9riels et \u00e9quipements sur les chantiers ne sont plus des faits isol\u00e9s. Ils touchent aujourd\u2019hui l\u2019ensemble du secteur du BTP, quelle que soit la taille de l\u2019entreprise ou la nature des travaux. <strong>Pour faire face \u00e0 cette menace permanente, qui pr\u00e9occupe de plus en plus de professionnels, ABUS, entreprise allemande de r\u00e9f\u00e9rence dans le domaine de la s\u00e9curit\u00e9, propose des solutions fiables et protectrices telles que la nouvelle serrure antivol VANLOCK pour v\u00e9hicules utilitaires ou le dispositif de s\u00e9curisation des conteneurs de stockage CONHASP 205.<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-justify\">Les vols d\u2019engins de chantier, de v\u00e9hicules avec leur contenu, de mat\u00e9riaux, d\u2019\u00e9quipements techniques, ainsi que les actes de malveillance constituent autant de risques auxquels les entreprises du b\u00e2timent sont confront\u00e9es. L\u2019impact \u00e9conomique est consid\u00e9rable : le co\u00fbt de ces vols et autres actes d\u00e9lictueux sur les chantiers est globalement \u00e9valu\u00e9 par la F\u00e9d\u00e9ration Fran\u00e7aise du B\u00e2timent (FFB) \u00e0 au moins 1 % du chiffre d\u2019affaires du secteur, soit plus d\u2019un milliard d\u2019euros.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Que ce soit pour un chantier, un v\u00e9hicule utilitaire ou un conteneur, ABUS propose une large gamme de solutions destin\u00e9es \u00e0 r\u00e9duire les risques de vol.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" width=\"720\" height=\"339\" src=\"https:\/\/i1.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2026\/05\/image-72.png?resize=720%2C339\" alt=\"\" class=\"wp-image-50600\" srcset=\"https:\/\/i1.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2026\/05\/image-72.png?w=1816&amp;ssl=1 1816w, https:\/\/i1.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2026\/05\/image-72.png?resize=768%2C361&amp;ssl=1 768w, https:\/\/i1.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2026\/05\/image-72.png?resize=432%2C203&amp;ssl=1 432w, https:\/\/i1.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2026\/05\/image-72.png?resize=396%2C186&amp;ssl=1 396w, https:\/\/i1.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2026\/05\/image-72.png?resize=1120%2C527&amp;ssl=1 1120w, https:\/\/i1.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2026\/05\/image-72.png?resize=660%2C310&amp;ssl=1 660w, https:\/\/i1.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2026\/05\/image-72.png?w=1440 1440w\" sizes=\"(max-width: 600px) 91vw, (max-width: 900px) 600px, (max-width: 1060px) 50vw, (max-width: 1200px) 520px, (max-width: 1400px) 43vw, 600px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<p class=\"has-large-font-size\">VANLOCK 241 ABUS<\/p>\n\n\n\n<p class=\"has-text-color\" style=\"color:#c72b2b;font-size:32px\">La serrure antivol pour v\u00e9hicules utilitaires<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Le vol de mat\u00e9riel ou d\u2019outillage dans les v\u00e9hicules utilitaires est un ph\u00e9nom\u00e8ne de plus en plus courant, qui peut s\u2019av\u00e9rer co\u00fbteux. Pour les professionnels mobiles, il est essentiel de pouvoir conserver leur \u00e9quipement en toute s\u00e9curit\u00e9 dans leur v\u00e9hicule.<\/p>\n\n\n\n<p class=\"has-text-align-justify\"><strong>Le VANLOCK 241 ABUS est un nouveau dispositif de verrouillage haute s\u00e9curit\u00e9 pour v\u00e9hicules utilitaires, adapt\u00e9 aux portes coulissantes lat\u00e9rales comme aux portes arri\u00e8re. Disponible en deux versions (1 ou 2 serrures), il offre une protection optimale contre les tentatives d\u2019effraction et de vol.<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-justify\">Facile \u00e0 installer, le VANLOCK 241 constitue une solution id\u00e9ale pour les professionnels amen\u00e9s \u00e0 effectuer de nombreuses ouvertures et fermetures. Ce dispositif de verrouillage peut \u00e9galement \u00eatre utilis\u00e9 pour s\u00e9curiser les portes d\u2019un garage ou d\u2019un local. Il est fabriqu\u00e9 \u00e0 partir de mat\u00e9riaux tr\u00e8s r\u00e9sistants : un corps robuste en acier renforc\u00e9 avec traitement anticorrosion, capable de r\u00e9sister aux attaques en force, ainsi qu\u2019un cylindre anti-per\u00e7age.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">\u00c0 noter : le VANLOCK 241 peut \u00eatre d\u00e9verrouill\u00e9 de l\u2019int\u00e9rieur \u00e0 l\u2019aide d\u2019un c\u00e2ble&nbsp;en inox.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Le VANLOCK 241 affiche un niveau de s\u00e9curit\u00e9 ABUS de 10\/10.<\/strong><\/p>\n\n\n\n<p><strong>Les + produit :<\/strong><\/p>\n\n\n\n<ul><li>\u2022 Compatible portes droites et portes gauches,<\/li><li>\u2022 Mat\u00e9riel de fixation et gabarit de montage inclus,<\/li><li>\u2022 Livr\u00e9 avec trois cl\u00e9s de s\u00e9curit\u00e9 ABUS,<\/li><li>\u2022 R\u00e9sistance \u00e9lev\u00e9e \u00e0 la corrosion,<\/li><li>\u2022 S\u2019adapte \u00e0 tous les mod\u00e8les de v\u00e9hicules utilitaires du march\u00e9.&nbsp;<\/li><\/ul>\n\n\n\n<p><strong>\u2022 VANLOCK 241 &#8211; 1 serrure antivol&nbsp;<\/strong><\/p>\n\n\n\n<p>Prix de vente public conseill\u00e9 : 149,50 euros<\/p>\n\n\n\n<p><strong>\u2022 VANLOCK 242 &#8211; 2 serrures antivol&nbsp;<\/strong><\/p>\n\n\n\n<p>Prix de vente public conseill\u00e9 : 279,50 euros<\/p>\n\n\n\n<p>Points de vente : grandes surfaces de bricolage, d\u00e9taillants et grossistes<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" width=\"720\" height=\"284\" src=\"https:\/\/i2.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2026\/05\/image-73.png?resize=720%2C284\" alt=\"\" class=\"wp-image-50601\" srcset=\"https:\/\/i2.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2026\/05\/image-73.png?w=1816&amp;ssl=1 1816w, https:\/\/i2.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2026\/05\/image-73.png?resize=768%2C302&amp;ssl=1 768w, https:\/\/i2.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2026\/05\/image-73.png?resize=432%2C170&amp;ssl=1 432w, https:\/\/i2.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2026\/05\/image-73.png?resize=396%2C156&amp;ssl=1 396w, https:\/\/i2.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2026\/05\/image-73.png?resize=1120%2C442&amp;ssl=1 1120w, https:\/\/i2.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2026\/05\/image-73.png?resize=660%2C260&amp;ssl=1 660w, https:\/\/i2.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2026\/05\/image-73.png?w=1440 1440w\" sizes=\"(max-width: 600px) 91vw, (max-width: 900px) 600px, (max-width: 1060px) 50vw, (max-width: 1200px) 520px, (max-width: 1400px) 43vw, 600px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<p class=\"has-large-font-size\">CONHASP 205 ABUS<\/p>\n\n\n\n<p class=\"has-text-color\" style=\"color:#c42929;font-size:33px\">Une s\u00e9curisation efficace des conteneurs<\/p>\n\n\n\n<p class=\"has-text-align-justify\"><strong>La s\u00e9curisation des conteneurs de transport ou de stockage contre le vol est essentielle pour prot\u00e9ger les biens qu\u2019ils contiennent. Le nouveau dispositif CONHASP 205 ABUS, \u00e0 la fois simple \u00e0 installer et efficace, r\u00e9pond pleinement \u00e0 cet objectif.<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-justify\">Sa conception permet de s\u00e9curiser efficacement les barres de verrouillage verticales des portes, sans n\u00e9cessiter de modification permanente du conteneur : aucun per\u00e7age ni soudure n\u2019est requis.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Ce syst\u00e8me en deux parties est fabriqu\u00e9 en acier ultra-r\u00e9sistant et int\u00e8gre des composants prot\u00e9g\u00e9s contre la corrosion, garantissant une long\u00e9vit\u00e9 optimale, m\u00eame dans des conditions ext\u00e9rieures difficiles. Sa grande polyvalence lui permet de s\u2019adapter aux barres de verrouillage dont l\u2019espacement est compris entre 225 mm et 480 mm.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Dispositif de haute s\u00e9curit\u00e9, le CONHASP 205 ABUS peut \u00eatre mont\u00e9 ou d\u00e9mont\u00e9 en quelques minutes seulement, sans laisser de traces. Le verrouillage final est assur\u00e9 par un cadenas compatible, \u00e9quip\u00e9 d\u2019un cylindre interchangeable \u00e0 profil europ\u00e9en (mod\u00e8les 37\/55HB38 ou 83\/60-5).<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Le CONHASP 205 affiche un niveau de s\u00e9curit\u00e9 ABUS de 10\/10.&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Les + produit :<\/strong><\/p>\n\n\n\n<p>\u2022 Compatible avec la majorit\u00e9 des conteneurs de transport et de stockage standards,&nbsp;<\/p>\n\n\n\n<p>\u2022 Aucune modification permanente requise : pas de per\u00e7age, de soudure ni d\u2019alt\u00e9ration du conteneur,<\/p>\n\n\n\n<p>\u2022 Montage et d\u00e9montage en quelques minutes,<\/p>\n\n\n\n<p>\u2022 Installation et retrait possibles \u00e0 tout moment, sans laisser de trace.<\/p>\n\n\n\n<p>Prix de vente publics conseill\u00e9s :&nbsp;<\/p>\n\n\n\n<p>\u2022 <strong>CONHASP 205 + cadenas 37\/55HB<\/strong> : 278,50 \u20ac<\/p>\n\n\n\n<p>\u2022 <strong>CONHASP 205 + cadenas 83\/60-5<\/strong> : 292,90 \u20ac<\/p>\n\n\n\n<p>Points de vente : grandes surfaces de bricolage, d\u00e9taillants et grossistes<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les vols de mat\u00e9riaux, mat\u00e9riels et \u00e9quipements sur les chantiers ne sont plus des faits isol\u00e9s. Ils touchent aujourd\u2019hui l\u2019ensemble du secteur du BTP, quelle que soit la taille de l\u2019entreprise ou la nature des travaux. Pour faire face \u00e0 cette menace permanente, qui pr\u00e9occupe de plus en plus de professionnels, ABUS, entreprise allemande de [&hellip;]<\/p>\n","protected":false},"author":41,"featured_media":50602,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"spay_email":""},"categories":[4,102],"tags":[2724],"jetpack_featured_media_url":"https:\/\/i1.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2026\/05\/ABUS-.jpg?fit=1513%2C825&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":982,"url":"https:\/\/batimedianews.com\/live\/index.php\/2019\/03\/26\/les-solutions-abus-pour-securiser-tous-les-equipements-sur-les-chantiers\/","url_meta":{"origin":50598,"position":0},"title":"Les solutions ABUS pour s\u00e9curiser tous les \u00e9quipements sur les chantiers","date":"26 mars 2019","format":false,"excerpt":"La recrudescence des vols de mat\u00e9riaux, mat\u00e9riels et \u00e9quipements sur les chantiers pr\u00e9occupe de plus en plus les entrepreneurs du b\u00e2timent. Au point que la s\u00e9curisation repr\u00e9sente pour eux un enjeu majeur. Avec ABUS, les professionnels trouveront les solutions protectrices et s\u00e9curitaires les mieux adapt\u00e9es \u00e0 leurs besoins. Un choix\u2026","rel":"","context":"Dans &quot;Actualit\u00e9 Entreprises&quot;","img":{"alt_text":"","src":"https:\/\/i2.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2019\/08\/abus_image.jpg?fit=1020%2C592&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":42861,"url":"https:\/\/batimedianews.com\/live\/index.php\/2025\/02\/13\/dom-metalux-devient-le-distributeur-exclusif-des-solutions-de-verrouillage-viro-aupres-des-revendeurs-en-france\/","url_meta":{"origin":50598,"position":1},"title":"DOM-Metalux devient le distributeur exclusif des solutions de verrouillage Viro aupr\u00e8s des revendeurs en France","date":"13 f\u00e9vrier 2025","format":false,"excerpt":"Suite \u00e0 l\u2019acquisition de Viro par DOM Security en 2023, DOM-Metalux, filiale du groupe, annonce int\u00e9grer \u00e0 son offre les solutions de verrouillage de la soci\u00e9t\u00e9 italienne comprenant ses produits phares historiques dont les cadenas de s\u00e9curit\u00e9, les serrures \u00e9lectriques et les syst\u00e8mes de s\u00e9curit\u00e9 pour v\u00e9hicules utilitaires et deux\u2026","rel":"","context":"Dans &quot;Actualit\u00e9 Entreprises&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2025\/02\/DOM-articles-.jpg?fit=825%2C825&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":45311,"url":"https:\/\/batimedianews.com\/live\/index.php\/2025\/06\/13\/nouveau-abus-onetm-toutes-les-cles-sur-une-seule-application-mobile\/","url_meta":{"origin":50598,"position":2},"title":"Nouveau ABUS OneTM &#8211; Toutes les cl\u00e9s sur une seule application mobile","date":"13 juin 2025","format":false,"excerpt":"ABUS, expert dans le domaine de la s\u00e9curit\u00e9 depuis 1924, propose des solutions innovantes pour la protection des biens et des personnes. Destin\u00e9s aux particuliers et aux professionnels, les produits Made in Germany ABUS ne cessent d\u2019\u00e9voluer pour rester \u00e0 la pointe de la technologie et r\u00e9pondre aux d\u00e9fis de\u2026","rel":"","context":"Dans &quot;Actualit\u00e9 Entreprises&quot;","img":{"alt_text":"","src":"https:\/\/i2.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2025\/06\/ABUS.jpg?fit=825%2C825&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":48210,"url":"https:\/\/batimedianews.com\/live\/index.php\/2025\/11\/27\/nouveau-catalogue-haute-securite-de-picard-serrures-un-guide-de-choix-clair-pour-que-chaque-particulier-selectionne-la-porte-blindee-ou-la-serrure-qui-protege-vraiment-son-foyer\/","url_meta":{"origin":50598,"position":3},"title":"Nouveau catalogue Haute S\u00e9curit\u00e9 de Picard Serrures : Un guide de choix clair pour que chaque particulier s\u00e9lectionne la porte blind\u00e9e ou la serrure qui prot\u00e8ge vraiment son foyer","date":"27 novembre 2025","format":false,"excerpt":"Fabricant fran\u00e7ais de solutions de s\u00e9curit\u00e9 depuis plus de 300 ans, PICARD SERRURES dispose d\u2019une large gamme de portes blind\u00e9es et d\u2019\u00e9quipements anti effraction (serrures, cylindres et cl\u00e9s) certifi\u00e9s, reconnus pour leur fiabilit\u00e9 et leur performance. Aujourd\u2019hui, l\u2019acteur incontournable dans son secteur r\u00e9unit l\u2019ensemble de ses produits adapt\u00e9s au march\u00e9\u2026","rel":"","context":"Dans &quot;Actualit\u00e9 Entreprises&quot;","img":{"alt_text":"","src":"https:\/\/i2.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2025\/11\/Picard.jpg?fit=825%2C825&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":32716,"url":"https:\/\/batimedianews.com\/live\/index.php\/2023\/11\/08\/intratone-commercialise-la-premiere-serrure-multipoints-connectee-de-la-marque-kibolt\/","url_meta":{"origin":50598,"position":4},"title":"INTRATONE commercialise la premi\u00e8re serrure multipoints connect\u00e9e de la marque KIBOLT","date":"8 novembre 2023","format":false,"excerpt":"Initiateur des syst\u00e8mes d\u2019interphonie et de contr\u00f4le d\u2019acc\u00e8s utilisant le r\u00e9seau GSM, COGELEC est l\u2019unique soci\u00e9t\u00e9 fran\u00e7aise \u00e0 proposer l\u2019ensemble de ses gammes de produits sans fil depuis plus de 15 ans. Forte de son domaine d\u2019expertise, l\u2019entreprise est devenue le leader en mati\u00e8re d\u2019interphonie et de contr\u00f4le d\u2019acc\u00e8s. Toujours\u2026","rel":"","context":"Dans &quot;fermetures&quot;","img":{"alt_text":"","src":"https:\/\/i2.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2023\/11\/intratone_cogelec-Image-articles-.jpg?fit=825%2C825&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1247,"url":"https:\/\/batimedianews.com\/live\/index.php\/2019\/05\/14\/armorgard-nouveau-coffre-de-chantier-tuffbank\/","url_meta":{"origin":50598,"position":5},"title":"Armorgard : Nouveau coffre de chantier TuffBank","date":"14 mai 2019","format":false,"excerpt":"Armorgard ajoute \u00e0 ses\u00a0coffres de chantier\u00a0s\u00e9curis\u00e9s de nouvelles\u00a0caract\u00e9ristiques les\u00a0rendant encore\u00a0plus s\u00fbrs \u00e0 utiliser,\u00a0r\u00e9sistants, solides et\u00a0quasiment inviolables. Armorgard lance la deuxi\u00e8me g\u00e9n\u00e9ration de sa gamme TuffBank, ajoutant \u00e0\u00a0ses coffres de chantiers s\u00e9curis\u00e9s de nouvelles caract\u00e9ristiques les rendant\u00a0encore plus s\u00fbrs \u00e0 utiliser, r\u00e9sistants, solides et quasiment inviolables. TuffBank a \u00e9t\u00e9 test\u00e9 selon\u2026","rel":"","context":"Dans &quot;Actualit\u00e9 Entreprises&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/batimedianews.com\/live\/wp-content\/uploads\/2019\/08\/armor_image.jpg?fit=1089%2C661&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/posts\/50598"}],"collection":[{"href":"https:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/comments?post=50598"}],"version-history":[{"count":2,"href":"https:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/posts\/50598\/revisions"}],"predecessor-version":[{"id":50618,"href":"https:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/posts\/50598\/revisions\/50618"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/media\/50602"}],"wp:attachment":[{"href":"https:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/media?parent=50598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/categories?post=50598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/batimedianews.com\/live\/index.php\/wp-json\/wp\/v2\/tags?post=50598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}